{"id":5364,"date":"2020-10-26T22:57:23","date_gmt":"2020-10-26T21:57:23","guid":{"rendered":"https:\/\/www.jcwerly.fr\/photo\/?p=5364"},"modified":"2020-10-26T23:00:31","modified_gmt":"2020-10-26T22:00:31","slug":"the-old-country-2","status":"publish","type":"post","link":"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/","title":{"rendered":"The Old Country 2"},"content":{"rendered":"\n<div class=\"wp-block-cover has-background-dim has-parallax\" style=\"background-image:url(https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-2.jpg);min-height:560px;aspect-ratio:unset;\"><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\">THE OLD COUNTRY 2<\/p>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-1 wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-15.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"959\" height=\"1100\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-15.jpg\" alt=\"\" data-id=\"5374\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-15.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-15\/\" class=\"wp-image-5374\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-15.jpg 959w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-15-768x881.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-15-508x583.jpg 508w\" sizes=\"auto, (max-width: 959px) 100vw, 959px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-14.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-14.jpg\" alt=\"\" data-id=\"5379\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-14.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-14\/\" class=\"wp-image-5379\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-14.jpg 1600w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-14-768x432.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-14-1536x864.jpg 1536w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-14-1240x698.jpg 1240w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-14-508x286.jpg 508w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-13.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"619\" height=\"1100\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-13.jpg\" alt=\"\" data-id=\"5378\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-13.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-13\/\" class=\"wp-image-5378\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-13.jpg 619w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-13-508x903.jpg 508w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"985\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-4.jpg\" alt=\"\" data-id=\"5368\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-4.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-4\/\" class=\"wp-image-5368\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-4.jpg 1600w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-4-768x473.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-4-1536x946.jpg 1536w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-4-1240x763.jpg 1240w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-4-508x313.jpg 508w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-7.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"766\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-7.jpg\" alt=\"\" data-id=\"5371\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-7.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-7\/\" class=\"wp-image-5371\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-7.jpg 1600w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-7-768x368.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-7-1536x735.jpg 1536w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-7-1240x594.jpg 1240w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-7-508x243.jpg 508w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-5.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-5.jpg\" alt=\"\" data-id=\"5369\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-5.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-5\/\" class=\"wp-image-5369\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-5.jpg 1600w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-5-768x512.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-5-1536x1024.jpg 1536w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-5-1240x827.jpg 1240w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-5-508x339.jpg 508w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-8.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1542\" height=\"1100\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-8.jpg\" alt=\"\" data-id=\"5372\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-8.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-8\/\" class=\"wp-image-5372\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-8.jpg 1542w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-8-768x548.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-8-1536x1096.jpg 1536w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-8-1240x885.jpg 1240w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-8-508x362.jpg 508w\" sizes=\"auto, (max-width: 1542px) 100vw, 1542px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"922\" height=\"1100\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-1.jpg\" alt=\"\" data-id=\"5365\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-1.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-1\/\" class=\"wp-image-5365\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-1.jpg 922w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-1-768x916.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-1-508x606.jpg 508w\" sizes=\"auto, (max-width: 922px) 100vw, 922px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"733\" height=\"1100\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-3.jpg\" alt=\"\" data-id=\"5367\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-3.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-3\/\" class=\"wp-image-5367\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-3.jpg 733w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-3-508x762.jpg 508w\" sizes=\"auto, (max-width: 733px) 100vw, 733px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"771\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-2.jpg\" alt=\"\" data-id=\"5366\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-2.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-2\/\" class=\"wp-image-5366\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-2.jpg 1600w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-2-768x370.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-2-1536x740.jpg 1536w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-2-1240x598.jpg 1240w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-2-508x245.jpg 508w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"806\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-6.jpg\" alt=\"\" data-id=\"5370\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-6.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-6\/\" class=\"wp-image-5370\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-6.jpg 1600w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-6-768x387.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-6-1536x774.jpg 1536w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-6-1240x625.jpg 1240w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-6-508x256.jpg 508w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-10.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-10.jpg\" alt=\"\" data-id=\"5375\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-10.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-10\/\" class=\"wp-image-5375\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-10.jpg 1600w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-10-768x432.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-10-1536x864.jpg 1536w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-10-1240x698.jpg 1240w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-10-508x286.jpg 508w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-11.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"619\" height=\"1100\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-11.jpg\" alt=\"\" data-id=\"5376\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-11.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-11\/\" class=\"wp-image-5376\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-11.jpg 619w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-11-508x903.jpg 508w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-12.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"619\" height=\"1100\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-12.jpg\" alt=\"\" data-id=\"5377\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-12.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-12\/\" class=\"wp-image-5377\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-12.jpg 619w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-12-508x903.jpg 508w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-9.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-9.jpg\" alt=\"\" data-id=\"5373\" data-full-url=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-9.jpg\" data-link=\"https:\/\/www.jcwerly.fr\/photo\/the-old-country-2\/the-old-country-2-9\/\" class=\"wp-image-5373\" srcset=\"https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-9.jpg 1600w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-9-768x432.jpg 768w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-9-1536x864.jpg 1536w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-9-1240x698.jpg 1240w, https:\/\/www.jcwerly.fr\/photo\/wp-content\/uploads\/The-old-country-2-9-508x286.jpg 508w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":5374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[167],"tags":[],"class_list":["post-5364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-the-old-country"],"_links":{"self":[{"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/posts\/5364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/comments?post=5364"}],"version-history":[{"count":3,"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/posts\/5364\/revisions"}],"predecessor-version":[{"id":5382,"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/posts\/5364\/revisions\/5382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/media\/5374"}],"wp:attachment":[{"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/media?parent=5364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/categories?post=5364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jcwerly.fr\/photo\/wp-json\/wp\/v2\/tags?post=5364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}